{"id":1744,"date":"2025-09-18T14:40:45","date_gmt":"2025-09-18T12:40:45","guid":{"rendered":"https:\/\/www.lra.at\/anwendungsfeld\/railway-safety-systems-for-freight-lines\/"},"modified":"2025-11-18T14:19:27","modified_gmt":"2025-11-18T13:19:27","slug":"railway-safety-systems-for-freight-lines","status":"publish","type":"anwendungsfeld","link":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/","title":{"rendered":"Railway Safety Systems for Freight Lines"},"content":{"rendered":"[av_one_full first min_height='' vertical_alignment='av-align-top' space='' row_boxshadow='' row_boxshadow_width='10' row_boxshadow_color='' custom_margin='' margin='0px' av-desktop-margin='' av-medium-margin='' av-small-margin='' av-mini-margin='' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' min_col_height='' padding='' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' column_boxshadow='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' src_dynamic='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location='' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location='' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location='' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location='' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location='' av-mini-css_position_z_index='' link='' link_dynamic='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' element_template='' one_element_template='' show_locked_options_fakearg='' av_uid='av-8tzgg' sc_version='1.0']\r\n\r\n[av_textblock fold_type='' fold_height='' fold_more='Weiterlesen' fold_less='Read less' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' padding='' padding_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-padding='' av-mini-padding_sync='true' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' container_tag='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' element_template='' one_element_template='' av_uid='av-mg17tiuk' sc_version='1.0' admin_preview_bg='']\r\n<h1>{acf_field_68cbebb05d242:Anwendungsfeld-Name}<\/h1>\r\n{acf_field_68ee0217fd50d:Anwendungsfeld-Beschreibung}\r\n\r\n[anwendungsfeld_zu_mitglied_list title=\"LRA members covering this application area:\"]\r\n[\/av_textblock]\r\n\r\n[av_codeblock wrapper_element='' wrapper_element_attributes='' codeblock_type='' alb_description='' id='' custom_class='' template_class='' av_uid='av-mg19u727' sc_version='1.0']\r\n<a href=\"#\" onclick=\"history.go(-1); return false;\">back to Application Area<\/a>\r\n[\/av_codeblock]\r\n\r\n[\/av_one_full]\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"leistungsbereich":[87],"class_list":["post-1744","anwendungsfeld","type-anwendungsfeld","status-publish","format-standard","hentry","leistungsbereich-mode-of-transport-rail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Railway Safety Systems for Freight Lines - LRA Logistics Research Austria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Railway Safety Systems for Freight Lines - LRA Logistics Research Austria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/\" \/>\n<meta property=\"og:site_name\" content=\"LRA Logistics Research Austria\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T13:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lra.at\/wp-content\/uploads\/lra-logo-dark-with-bg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/\",\"url\":\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/\",\"name\":\"Railway Safety Systems for Freight Lines - LRA Logistics Research Austria\",\"isPartOf\":{\"@id\":\"https:\/\/www.lra.at\/en\/#website\"},\"datePublished\":\"2025-09-18T12:40:45+00:00\",\"dateModified\":\"2025-11-18T13:19:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lra.at\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Railway Safety Systems for Freight Lines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lra.at\/en\/#website\",\"url\":\"https:\/\/www.lra.at\/en\/\",\"name\":\"LRA Logistics Research Austria\",\"description\":\"Die Logistikforschungskompetenz \u00d6sterreichs\",\"publisher\":{\"@id\":\"https:\/\/www.lra.at\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lra.at\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lra.at\/en\/#organization\",\"name\":\"LRA Logistics Research Austria\",\"url\":\"https:\/\/www.lra.at\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lra.at\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lra.at\/wp-content\/uploads\/lra-icon-hero-bg.png\",\"contentUrl\":\"https:\/\/www.lra.at\/wp-content\/uploads\/lra-icon-hero-bg.png\",\"width\":1400,\"height\":1434,\"caption\":\"LRA Logistics Research Austria\"},\"image\":{\"@id\":\"https:\/\/www.lra.at\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/lra-logistics-research-austria\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Railway Safety Systems for Freight Lines - LRA Logistics Research Austria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/","og_locale":"en_US","og_type":"article","og_title":"Railway Safety Systems for Freight Lines - LRA Logistics Research Austria","og_url":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/","og_site_name":"LRA Logistics Research Austria","article_modified_time":"2025-11-18T13:19:27+00:00","og_image":[{"width":800,"height":347,"url":"https:\/\/www.lra.at\/wp-content\/uploads\/lra-logo-dark-with-bg.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/","url":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/","name":"Railway Safety Systems for Freight Lines - LRA Logistics Research Austria","isPartOf":{"@id":"https:\/\/www.lra.at\/en\/#website"},"datePublished":"2025-09-18T12:40:45+00:00","dateModified":"2025-11-18T13:19:27+00:00","breadcrumb":{"@id":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lra.at\/en\/application-areas\/railway-safety-systems-for-freight-lines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lra.at\/en\/"},{"@type":"ListItem","position":2,"name":"Railway Safety Systems for Freight Lines"}]},{"@type":"WebSite","@id":"https:\/\/www.lra.at\/en\/#website","url":"https:\/\/www.lra.at\/en\/","name":"LRA Logistics Research Austria","description":"Die Logistikforschungskompetenz \u00d6sterreichs","publisher":{"@id":"https:\/\/www.lra.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lra.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lra.at\/en\/#organization","name":"LRA Logistics Research Austria","url":"https:\/\/www.lra.at\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lra.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lra.at\/wp-content\/uploads\/lra-icon-hero-bg.png","contentUrl":"https:\/\/www.lra.at\/wp-content\/uploads\/lra-icon-hero-bg.png","width":1400,"height":1434,"caption":"LRA Logistics Research Austria"},"image":{"@id":"https:\/\/www.lra.at\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/lra-logistics-research-austria\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lra.at\/en\/wp-json\/wp\/v2\/anwendungsfeld\/1744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lra.at\/en\/wp-json\/wp\/v2\/anwendungsfeld"}],"about":[{"href":"https:\/\/www.lra.at\/en\/wp-json\/wp\/v2\/types\/anwendungsfeld"}],"wp:attachment":[{"href":"https:\/\/www.lra.at\/en\/wp-json\/wp\/v2\/media?parent=1744"}],"wp:term":[{"taxonomy":"leistungsbereich","embeddable":true,"href":"https:\/\/www.lra.at\/en\/wp-json\/wp\/v2\/leistungsbereich?post=1744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}